{"id":4890,"date":"2025-04-04T07:57:57","date_gmt":"2025-04-04T05:57:57","guid":{"rendered":"https:\/\/www.pharmacie-homeopathie.com\/blog\/?p=4890"},"modified":"2025-04-04T07:57:57","modified_gmt":"2025-04-04T05:57:57","slug":"combattre-les-calculs-urinaires","status":"publish","type":"post","link":"https:\/\/www.pharmacie-homeopathie.com\/blog\/combattre-les-calculs-urinaires\/","title":{"rendered":"Combattre les calculs urinaires"},"content":{"rendered":"<h2>Les gestes simples pour \u00e9viter les r\u00e9cidives<\/h2>\n<p>Les calculs r\u00e9naux ou lithiases urinaires sont comparables \u00e0 de petits \u00ab cailloux \u00bb qui se forment dans les reins et qui peuvent obstruer les voies urinaires en g\u00e9n\u00e9rant d\u2019intenses douleurs. Lorsqu\u2019ils sont de petites tailles, avec un diam\u00e8tre inf\u00e9rieur \u00e0 5 mm, ils peuvent s\u2019\u00e9vacuer spontan\u00e9ment, toutefois lorsqu\u2019ils sont plus gros, les techniques chirurgicales sont n\u00e9cessaires, notamment la lithotripsie qui permet de pulv\u00e9riser les calculs afin de faciliter leur \u00e9limination par les voies naturelles.<\/p>\n<p><a href=\"https:\/\/www.pharmacie-homeopathie.com\/blog\/wp-content\/uploads\/2025\/03\/Rein-pharmacie-PHC.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4908 size-full\" title=\"Combattre les calculs urinaires\" src=\"https:\/\/www.pharmacie-homeopathie.com\/blog\/wp-content\/uploads\/2025\/03\/Rein-pharmacie-PHC.jpg\" alt=\"Combattre les calculs urinaires\" width=\"1024\" height=\"644\" srcset=\"https:\/\/www.pharmacie-homeopathie.com\/blog\/wp-content\/uploads\/2025\/03\/Rein-pharmacie-PHC.jpg 1024w, https:\/\/www.pharmacie-homeopathie.com\/blog\/wp-content\/uploads\/2025\/03\/Rein-pharmacie-PHC-300x189.jpg 300w, https:\/\/www.pharmacie-homeopathie.com\/blog\/wp-content\/uploads\/2025\/03\/Rein-pharmacie-PHC-768x483.jpg 768w, https:\/\/www.pharmacie-homeopathie.com\/blog\/wp-content\/uploads\/2025\/03\/Rein-pharmacie-PHC-232x146.jpg 232w, https:\/\/www.pharmacie-homeopathie.com\/blog\/wp-content\/uploads\/2025\/03\/Rein-pharmacie-PHC-50x31.jpg 50w, https:\/\/www.pharmacie-homeopathie.com\/blog\/wp-content\/uploads\/2025\/03\/Rein-pharmacie-PHC-119x75.jpg 119w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<p>On estime que 4% de la population est concern\u00e9 par les lithiases urinaires avec une pr\u00e9dominance chez les hommes \u00e2g\u00e9s de 30 et 50 ans. On distingue deux grandes familles de lithiases urinaires selon leur composition : les calculs calciques (pr\u00e8s de 90% des cas) et les non calciques.<\/p>\n<table width=\"100%\">\n<tbody>\n<tr>\n<td rowspan=\"3\"><strong>Calculs calciques<\/strong><\/td>\n<td>Oxalate de calcium<\/td>\n<\/tr>\n<tr>\n<td>Oxalate de phosphate de calcium<\/td>\n<\/tr>\n<tr>\n<td>Phosphate de calcium<\/td>\n<\/tr>\n<tr>\n<td rowspan=\"5\"><strong>Calculs non calciques<\/strong><\/td>\n<td>Phospho-ammoniaco-magn\u00e9siens (struvite)<\/td>\n<\/tr>\n<tr>\n<td>Cystine<\/td>\n<\/tr>\n<tr>\n<td>Acide urique<\/td>\n<\/tr>\n<tr>\n<td>Xanthine<\/td>\n<\/tr>\n<tr>\n<td>M\u00e9dicamenteux (antir\u00e9troviraux)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Les calculs r\u00e9naux les plus courants sont ceux compos\u00e9s d&#8217;oxalate de calcium. Ils sont suivis par les lithiases constitu\u00e9es d&#8217;oxalate de phosphate de calcium et par celles compos\u00e9es de phosphate de calcium. En revanche, les calculs d\u2019acide urique ne concernent qu\u2019une personne sur 10 environ, les calculs phospho-ammoniaco-magn\u00e9siens ne touchent que 3 individus sur 100 et les calculs de cystine, plus rares, seulement 1 individu sur 100.<\/p>\n<p>La formation des calculs est bien souvent en lien avec la modification du pH urinaire et certains comportements alimentaires (manque d\u2019hydratation, alimentation riche en calcium ou en oxalate, en prot\u00e9ines, en purine, en sel, en sucre raffin\u00e9) mais elle peut aussi \u00eatre en lien avec d\u2019autres facteurs favorisants tels que la s\u00e9dentarit\u00e9, l\u2019ob\u00e9sit\u00e9, la prise de certains m\u00e9dicaments, la survenue d\u2019infections urinaires, la goutte ou \u00eatre provoqu\u00e9e par d\u2019autres pathologies (maladies cong\u00e9nitales et anomalies des voies urinaires acquises).<\/p>\n<table width=\"100%\">\n<tbody>\n<tr>\n<td>\u00a0<strong>Facteurs de risque<\/strong><\/td>\n<td><strong>Type de calcul<\/strong><\/td>\n<\/tr>\n<tr>\n<td>D\u00e9shydratation r\u00e9p\u00e9t\u00e9e (surtout l\u2019\u00e9t\u00e9)<\/td>\n<td>Tous types<\/td>\n<\/tr>\n<tr>\n<td>Exc\u00e8s de calcium dans les urines<\/td>\n<td>Oxalate de calcium<\/td>\n<\/tr>\n<tr>\n<td>Exc\u00e8s d\u2019acide oxalique dans les urines<\/td>\n<td>Oxalate de calcium<\/td>\n<\/tr>\n<tr>\n<td>Intoxication m\u00e9dicamenteuse \u00e0 la vitamine C ou \u00e0 la vitamine D<\/td>\n<td>Oxalate de calcium<\/td>\n<\/tr>\n<tr>\n<td>D\u00e9ficit de citrate dans les urines<\/td>\n<td>Oxalate de calcium, oxalate de phosphate de calcium, phosphate de calcium<\/td>\n<\/tr>\n<tr>\n<td>Infection urinaire<\/td>\n<td>Phospho-ammoniaco-magn\u00e9siens (struvite)<\/td>\n<\/tr>\n<tr>\n<td>Cystinurie (maladie rare h\u00e9r\u00e9ditaire)<\/td>\n<td>Cystine<\/td>\n<\/tr>\n<tr>\n<td>Xanthinurie (maladie rare h\u00e9r\u00e9ditaire)<\/td>\n<td>Xanthine<\/td>\n<\/tr>\n<tr>\n<td>Goutte<\/td>\n<td>Acide urique<\/td>\n<\/tr>\n<tr>\n<td>Affections my\u00e9loprolif\u00e9ratives<\/td>\n<td>Acide urique<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2>Quels conseils permettent de r\u00e9duire les risques de formation de calculs r\u00e9naux ?<\/h2>\n<p>Une bonne hydratation constitue un principe de base \u00e0 respecter, quel que soit le type de lithiase. En effet, boire plus de 2 litres d\u2019eau par jour permet de diluer suffisamment les urines de fa\u00e7on \u00e0 diminuer le risque de cristallisation.<br \/>\nDans le cas des calculs calciques, il convient de r\u00e9duire le sel, les prot\u00e9ines animales, le chocolat, le th\u00e9 noir et la vitamine C. En outre, plusieurs aliments sont connus pour leur richesse en oxalate et il convient d\u2019en limiter la consommation. Il s\u2019agit notamment des \u00e9pinards, de la rhubarbe, des betteraves, de l\u2019oseille, des fruits \u00e0 coque, des pommes de terre (avec la peau), du son de bl\u00e9 ou du carambole.<\/p>\n<p>A l\u2019inverse, vous pouvez vous faire plaisir avec des aliments tr\u00e8s pauvres en oxalate tels que la laitue, les radis, les oignons, le concombre, les courges et courgettes, le ma\u00efs, le brocolis ainsi que les fruits suivants : banane, abricot, nectarine, p\u00eache, raisins, past\u00e8que, pommes ou encore m\u00fbres. Il est aussi recommand\u00e9 de consommer des eaux pauvres en calcium ainsi que de l\u2019eau citronn\u00e9e qui a un effet alcalinisant apr\u00e8s m\u00e9tabolisation.<\/p>\n<p>Dans le cas de la lithiase urique, il conseill\u00e9 de boire l\u2019eau de Vichy, d\u2019avoir un apport mod\u00e9r\u00e9 en prot\u00e9ines et pauvre en purines c\u2019est-\u00e0-dire limiter la charcuterie, les crustac\u00e9s et fruits de mer, les anchois, les sardines, les abats, le gibier, les champignons, la bi\u00e8re et les sodas contenant du fructose. Il faut aussi veiller \u00e0 ne pas prendre de compl\u00e9ments alimentaires \u00e0 base de levure de bi\u00e8re.<br \/>\nAttention toutefois \u00e0 ne pas tomber dans l\u2019exc\u00e8s et \u00e0 supprimer compl\u00e8tement des aliments que vous appr\u00e9ciez et auxquels vous tenez. La mod\u00e9ration et la diversification sont les ma\u00eetres-mots pour parvenir \u00e0 un \u00e9quilibre sain et durable.<\/p>\n<p>Dans le cas de la lithiase cystinique, le m\u00e9decin vous recommandera de boire environ 3 \u00e0 4 L d\u2019eau de Vichy par jour et si cela s\u2019av\u00e8re insuffisant, il sera susceptible de vous prescrire un m\u00e9dicament \u00e0 base de penicillamine.<\/p>\n<p>Enfin, pour ce qui est des calculs phospho-ammoniaco-magn\u00e9siens, le traitement pr\u00e9ventif repose sur la st\u00e9rilisation des urines gr\u00e2ce \u00e0 des antibiotiques.<\/p>\n<p>En r\u00e9sum\u00e9, adopter une hygi\u00e8ne de vie \u00e9quilibr\u00e9e et des habitudes alimentaires adapt\u00e9es peut jouer un r\u00f4le crucial dans la pr\u00e9vention des calculs urinaires. Prendre soin de ses reins, c&#8217;est \u00e9galement prendre soin de son bien-\u00eatre global. Un bonne hydratation associ\u00e9e \u00e0 quelques ajustements au quotidien, m\u00eame modestes, peuvent faire une grande diff\u00e9rence. Consultez toujours un professionnel de sant\u00e9 pour un accompagnement personnalis\u00e9 et adapt\u00e9 \u00e0 vos besoins sp\u00e9cifiques.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les gestes simples pour \u00e9viter les r\u00e9cidives Les calculs r\u00e9naux ou lithiases urinaires sont comparables \u00e0 de petits \u00ab cailloux \u00bb qui se forment dans les<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":3,"featured_media":4908,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-4890","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actu-sante"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Combattre les calculs urinaires<\/title>\n<meta name=\"description\" content=\"Les calculs r\u00e9naux ou lithiases urinaires sont comparables \u00e0 de petits \u00ab cailloux \u00bb qui se forment dans les reins.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pharmacie-homeopathie.com\/blog\/combattre-les-calculs-urinaires\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Combattre les calculs urinaires\" \/>\n<meta property=\"og:description\" content=\"Les calculs r\u00e9naux ou lithiases urinaires sont comparables \u00e0 de petits \u00ab cailloux \u00bb qui se forment dans les reins.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pharmacie-homeopathie.com\/blog\/combattre-les-calculs-urinaires\/\" \/>\n<meta property=\"og:site_name\" content=\"HOMEO EXPERT\u00ae\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/HomeoExpert\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/HomeoExpert\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-04T05:57:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pharmacie-homeopathie.com\/blog\/wp-content\/uploads\/2025\/03\/Rein-pharmacie-PHC.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"644\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"H\u00e9l\u00e8ne Gaillard - Pharmacienne \u00e0 la PHC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@HBerrueGaillard\" \/>\n<meta name=\"twitter:site\" content=\"@PharmaHomeo\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"H\u00e9l\u00e8ne Gaillard - Pharmacienne \u00e0 la PHC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Combattre les calculs urinaires","description":"Les calculs r\u00e9naux ou lithiases urinaires sont comparables \u00e0 de petits \u00ab cailloux \u00bb qui se forment dans les reins.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pharmacie-homeopathie.com\/blog\/combattre-les-calculs-urinaires\/","og_locale":"fr_FR","og_type":"article","og_title":"Combattre les calculs urinaires","og_description":"Les calculs r\u00e9naux ou lithiases urinaires sont comparables \u00e0 de petits \u00ab cailloux \u00bb qui se forment dans les reins.","og_url":"https:\/\/www.pharmacie-homeopathie.com\/blog\/combattre-les-calculs-urinaires\/","og_site_name":"HOMEO EXPERT\u00ae","article_publisher":"https:\/\/www.facebook.com\/HomeoExpert\/","article_author":"https:\/\/www.facebook.com\/HomeoExpert","article_published_time":"2025-04-04T05:57:57+00:00","og_image":[{"width":1024,"height":644,"url":"https:\/\/www.pharmacie-homeopathie.com\/blog\/wp-content\/uploads\/2025\/03\/Rein-pharmacie-PHC.jpg","type":"image\/jpeg"}],"author":"H\u00e9l\u00e8ne Gaillard - Pharmacienne \u00e0 la PHC","twitter_card":"summary_large_image","twitter_creator":"@HBerrueGaillard","twitter_site":"@PharmaHomeo","twitter_misc":{"\u00c9crit par":"H\u00e9l\u00e8ne Gaillard - Pharmacienne \u00e0 la PHC","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.pharmacie-homeopathie.com\/blog\/combattre-les-calculs-urinaires\/#article","isPartOf":{"@id":"https:\/\/www.pharmacie-homeopathie.com\/blog\/combattre-les-calculs-urinaires\/"},"author":{"name":"H\u00e9l\u00e8ne Gaillard - Pharmacienne \u00e0 la PHC","@id":"https:\/\/www.pharmacie-homeopathie.com\/blog\/#\/schema\/person\/da8c737b6b3ffd91c8a027a379df93c4"},"headline":"Combattre les calculs urinaires","datePublished":"2025-04-04T05:57:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.pharmacie-homeopathie.com\/blog\/combattre-les-calculs-urinaires\/"},"wordCount":893,"commentCount":0,"publisher":{"@id":"https:\/\/www.pharmacie-homeopathie.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.pharmacie-homeopathie.com\/blog\/combattre-les-calculs-urinaires\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pharmacie-homeopathie.com\/blog\/wp-content\/uploads\/2025\/03\/Rein-pharmacie-PHC.jpg","articleSection":["Nos conseils"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.pharmacie-homeopathie.com\/blog\/combattre-les-calculs-urinaires\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.pharmacie-homeopathie.com\/blog\/combattre-les-calculs-urinaires\/","url":"https:\/\/www.pharmacie-homeopathie.com\/blog\/combattre-les-calculs-urinaires\/","name":"Combattre les calculs urinaires","isPartOf":{"@id":"https:\/\/www.pharmacie-homeopathie.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pharmacie-homeopathie.com\/blog\/combattre-les-calculs-urinaires\/#primaryimage"},"image":{"@id":"https:\/\/www.pharmacie-homeopathie.com\/blog\/combattre-les-calculs-urinaires\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pharmacie-homeopathie.com\/blog\/wp-content\/uploads\/2025\/03\/Rein-pharmacie-PHC.jpg","datePublished":"2025-04-04T05:57:57+00:00","description":"Les calculs r\u00e9naux ou lithiases urinaires sont comparables \u00e0 de petits \u00ab cailloux \u00bb qui se forment dans les reins.","breadcrumb":{"@id":"https:\/\/www.pharmacie-homeopathie.com\/blog\/combattre-les-calculs-urinaires\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pharmacie-homeopathie.com\/blog\/combattre-les-calculs-urinaires\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.pharmacie-homeopathie.com\/blog\/combattre-les-calculs-urinaires\/#primaryimage","url":"https:\/\/www.pharmacie-homeopathie.com\/blog\/wp-content\/uploads\/2025\/03\/Rein-pharmacie-PHC.jpg","contentUrl":"https:\/\/www.pharmacie-homeopathie.com\/blog\/wp-content\/uploads\/2025\/03\/Rein-pharmacie-PHC.jpg","width":1024,"height":644,"caption":"Combattre les calculs urinaires"},{"@type":"BreadcrumbList","@id":"https:\/\/www.pharmacie-homeopathie.com\/blog\/combattre-les-calculs-urinaires\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.pharmacie-homeopathie.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Nos conseils","item":"https:\/\/www.pharmacie-homeopathie.com\/blog\/category\/actu-sante\/"},{"@type":"ListItem","position":3,"name":"Combattre les calculs urinaires"}]},{"@type":"WebSite","@id":"https:\/\/www.pharmacie-homeopathie.com\/blog\/#website","url":"https:\/\/www.pharmacie-homeopathie.com\/blog\/","name":"HOMEO EXPERT\u00ae","description":"Le blog de la Pharmacie Hom\u00e9opathique Centrale \u00e0 Paris","publisher":{"@id":"https:\/\/www.pharmacie-homeopathie.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pharmacie-homeopathie.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.pharmacie-homeopathie.com\/blog\/#organization","name":"Pharmacie Hom\u00e9opathique Centrale Paris - PHC","url":"https:\/\/www.pharmacie-homeopathie.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.pharmacie-homeopathie.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.pharmacie-homeopathie.com\/blog\/wp-content\/uploads\/2018\/11\/phc-logo.png","contentUrl":"https:\/\/www.pharmacie-homeopathie.com\/blog\/wp-content\/uploads\/2018\/11\/phc-logo.png","width":280,"height":113,"caption":"Pharmacie Hom\u00e9opathique Centrale Paris - PHC"},"image":{"@id":"https:\/\/www.pharmacie-homeopathie.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/HomeoExpert\/","https:\/\/x.com\/PharmaHomeo","https:\/\/www.youtube.com\/channel\/UCjrIcslKFiRvnhDZ26jyXYQ","https:\/\/www.pinterest.fr\/pin\/103864335143240482\/"]},{"@type":"Person","@id":"https:\/\/www.pharmacie-homeopathie.com\/blog\/#\/schema\/person\/da8c737b6b3ffd91c8a027a379df93c4","name":"H\u00e9l\u00e8ne Gaillard - Pharmacienne \u00e0 la PHC","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.pharmacie-homeopathie.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/62bb826f364c8f69694d23642e4dbaa9ef15bdd269e8ad2f38e407c43ba0b8ca?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/62bb826f364c8f69694d23642e4dbaa9ef15bdd269e8ad2f38e407c43ba0b8ca?s=96&d=blank&r=g","caption":"H\u00e9l\u00e8ne Gaillard - Pharmacienne \u00e0 la PHC"},"sameAs":["https:\/\/www.facebook.com\/HomeoExpert","https:\/\/www.linkedin.com\/in\/hlne-berrue-gaillard-7668202a\/","https:\/\/x.com\/HBerrueGaillard"]}]}},"_links":{"self":[{"href":"https:\/\/www.pharmacie-homeopathie.com\/blog\/wp-json\/wp\/v2\/posts\/4890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pharmacie-homeopathie.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pharmacie-homeopathie.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pharmacie-homeopathie.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pharmacie-homeopathie.com\/blog\/wp-json\/wp\/v2\/comments?post=4890"}],"version-history":[{"count":6,"href":"https:\/\/www.pharmacie-homeopathie.com\/blog\/wp-json\/wp\/v2\/posts\/4890\/revisions"}],"predecessor-version":[{"id":4909,"href":"https:\/\/www.pharmacie-homeopathie.com\/blog\/wp-json\/wp\/v2\/posts\/4890\/revisions\/4909"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pharmacie-homeopathie.com\/blog\/wp-json\/wp\/v2\/media\/4908"}],"wp:attachment":[{"href":"https:\/\/www.pharmacie-homeopathie.com\/blog\/wp-json\/wp\/v2\/media?parent=4890"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pharmacie-homeopathie.com\/blog\/wp-json\/wp\/v2\/categories?post=4890"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pharmacie-homeopathie.com\/blog\/wp-json\/wp\/v2\/tags?post=4890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}